{"id":2874,"date":"2019-11-05T11:14:08","date_gmt":"2019-11-05T10:14:08","guid":{"rendered":"https:\/\/chicriviera.com\/?p=2874"},"modified":"2024-04-07T11:18:06","modified_gmt":"2024-04-07T09:18:06","slug":"les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole","status":"publish","type":"post","link":"https:\/\/chicriviera.com\/de\/2019\/11\/05\/kostenlose-museen-a-nice-fur-alle-einwohner-der-metropole\/","title":{"rendered":"Kostenlose Museen in Nizza f\u00fcr alle Einwohner der Metropole"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Wussten Sie schon? Mit dem <strong>MUSEUMSPASS VON NIZZA<\/strong>Mit diesem Pass haben alle B\u00fcrger von Nizza und alle Einwohner der Metropolregion drei Jahre lang (G\u00fcltigkeit des Passes) freien Eintritt in alle Museen und Galerien. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1242\" height=\"1552\" src=\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/7674e1ab-7b7f-45ae-9cbb-f715e3cff3d8.jpg\" alt=\"\" class=\"wp-image-2885\" srcset=\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/7674e1ab-7b7f-45ae-9cbb-f715e3cff3d8.jpg 1242w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/7674e1ab-7b7f-45ae-9cbb-f715e3cff3d8-240x300.jpg 240w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/7674e1ab-7b7f-45ae-9cbb-f715e3cff3d8-768x960.jpg 768w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/7674e1ab-7b7f-45ae-9cbb-f715e3cff3d8-819x1024.jpg 819w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/7674e1ab-7b7f-45ae-9cbb-f715e3cff3d8-600x750.jpg 600w\" sizes=\"(max-width: 1242px) 100vw, 1242px\" \/><figcaption>Museum der Sch\u00f6nen K\u00fcnste <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Was ist die Metropole? Die Metropole ist die erste in Frankreich und ist eine interkommunale Struktur um die Stadt Nizza herum, die 49 Gemeinden umfasst. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1242\" height=\"916\" src=\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/0698e81d-95b0-4dd7-bdb0-18e569f59494.jpg\" alt=\"\" class=\"wp-image-2887\" srcset=\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/0698e81d-95b0-4dd7-bdb0-18e569f59494.jpg 1242w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/0698e81d-95b0-4dd7-bdb0-18e569f59494-300x221.jpg 300w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/0698e81d-95b0-4dd7-bdb0-18e569f59494-768x566.jpg 768w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/0698e81d-95b0-4dd7-bdb0-18e569f59494-1024x755.jpg 1024w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/0698e81d-95b0-4dd7-bdb0-18e569f59494-600x443.jpg 600w\" sizes=\"(max-width: 1242px) 100vw, 1242px\" \/><figcaption>Museum der Fotografie Charles N\u00e8gre<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Welche Gemeinden geh\u00f6ren zur Metropole? : <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aspremont - Bairols - Beaulieu-sur-Mer - Belv\u00e9d\u00e8re - Bonson - Cagnes-sur-Mer - Cap-d'Ail - Carros - Castagniers - Clans - Colmars - Duranus - Eze - Falicon - Gatti\u00e8res - Gillette - Ilonse - Isola - La Bol\u00e8ne-.V\u00e9subie - La Gaude - La Roquette-sur-Var - La Tour - La Trinit\u00e9 - Lantosque - Le Broc - Levens - Marie - Nice - Rimplas - Roquebilli\u00e8re - Roublon - Roure - SaintAndr\u00e9-de-la-Roche - Saint-Blaise - Saint-Dalmas-le-Selvage - Saint-\u00c9tienne-de-Tin\u00e9e - Saint-Jean-Cap-Ferrat - Saint-Jeannet - Saint-Laurent-du-Var - Saint-Martin-du-Var - Saint-Martin-V\u00e9subie- Saint-Sauveur-sur-Tin\u00e9e - Tournefort - Tourrette-Levens - Utelle - Valdeblore - Venanson - Vence - Villefranche-sur-Mer. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/da894b88-5b80-4530-b89c-2dff5e67c9f4.jpg\" alt=\"\" class=\"wp-image-2889\" srcset=\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/da894b88-5b80-4530-b89c-2dff5e67c9f4.jpg 1200w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/da894b88-5b80-4530-b89c-2dff5e67c9f4-300x200.jpg 300w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/da894b88-5b80-4530-b89c-2dff5e67c9f4-768x512.jpg 768w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/da894b88-5b80-4530-b89c-2dff5e67c9f4-1024x683.jpg 1024w, https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/da894b88-5b80-4530-b89c-2dff5e67c9f4-600x400.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption>Terra-Amata-Museum<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Wie erh\u00e4lt man den Pass? Ab 18 Jahren (freier Eintritt f\u00fcr Personen unter 18 Jahren) k\u00f6nnen Sie sich mit zwei Dokumenten am Empfang eines der Museen melden: einem g\u00fcltigen Ausweis und einem Nachweis \u00fcber Ihren Wohnsitz, der nicht \u00e4lter als drei Jahre sein darf, damit Ihnen Ihr pers\u00f6nlicher Pass vor Ort ausgestellt werden kann. Der Pass ist kostenlos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viel Spa\u00df beim Besuch! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Le saviez-vous? Avec le PASS MUS\u00c9ES DE NICE, tous les ni\u00e7ois mais aussi tous les habitants de la M\u00e9tropole ont acc\u00e8s gratuitement \u00e0 tous les mus\u00e9es et galeries, pendant 3 ans( validit\u00e9 du pass). Qu\u2019est ce que la M\u00e9tropole? Premi\u00e8re en France, c\u2019est une structure intercommunale autour de la ville de Nice, qui regroupe 49 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2893,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[27,337,335],"tags":[],"class_list":["post-2874","post","type-post","status-publish","format-standard","has-post-thumbnail","category-activites","category-france","category-nice","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole - Chic Riviera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chicriviera.com\/de\/2019\/11\/05\/kostenlose-museen-a-nice-fur-alle-einwohner-der-metropole\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole - Chic Riviera\" \/>\n<meta property=\"og:description\" content=\"Le saviez-vous? Avec le PASS MUS\u00c9ES DE NICE, tous les ni\u00e7ois mais aussi tous les habitants de la M\u00e9tropole ont acc\u00e8s gratuitement \u00e0 tous les mus\u00e9es et galeries, pendant 3 ans( validit\u00e9 du pass). Qu\u2019est ce que la M\u00e9tropole? Premi\u00e8re en France, c\u2019est une structure intercommunale autour de la ville de Nice, qui regroupe 49 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chicriviera.com\/de\/2019\/11\/05\/kostenlose-museen-a-nice-fur-alle-einwohner-der-metropole\/\" \/>\n<meta property=\"og:site_name\" content=\"Chic Riviera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ChicRivieracom\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-05T10:14:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-07T09:18:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"910\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Chic_Riviera\" \/>\n<meta name=\"twitter:site\" content=\"@Chic_Riviera\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\/\/chicriviera.com\/es\/#\/schema\/person\/c563ec1d9481b6d038092938cde95a4b\"},\"headline\":\"Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole\",\"datePublished\":\"2019-11-05T10:14:08+00:00\",\"dateModified\":\"2024-04-07T09:18:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/chicriviera.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg\",\"articleSection\":[\"Activit\u00e9s\",\"France\",\"Nice\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/\",\"url\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/\",\"name\":\"Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole - Chic Riviera\",\"isPartOf\":{\"@id\":\"https:\/\/chicriviera.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg\",\"datePublished\":\"2019-11-05T10:14:08+00:00\",\"dateModified\":\"2024-04-07T09:18:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage\",\"url\":\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg\",\"contentUrl\":\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg\",\"width\":910,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/chicriviera.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chicriviera.com\/es\/#website\",\"url\":\"https:\/\/chicriviera.com\/es\/\",\"name\":\"Chic Riviera\",\"description\":\"Le meilleur de la C\u00f4te d&#039;Azur : Restaurants, Plages, Sorties\",\"publisher\":{\"@id\":\"https:\/\/chicriviera.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chicriviera.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chicriviera.com\/es\/#organization\",\"name\":\"Chic Riviera\",\"url\":\"https:\/\/chicriviera.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/chicriviera.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/03\/cropped-crfavicon.png\",\"contentUrl\":\"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/03\/cropped-crfavicon.png\",\"width\":512,\"height\":512,\"caption\":\"Chic Riviera\"},\"image\":{\"@id\":\"https:\/\/chicriviera.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ChicRivieracom\/\",\"https:\/\/x.com\/Chic_Riviera\",\"https:\/\/www.instagram.com\/chicriviera\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/chicriviera.com\/es\/#\/schema\/person\/c563ec1d9481b6d038092938cde95a4b\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/chicriviera.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0bb721c49cd74f5b36020571509cc39351075de1991c6145cdbecbab8cf22c82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0bb721c49cd74f5b36020571509cc39351075de1991c6145cdbecbab8cf22c82?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"url\":\"https:\/\/chicriviera.com\/de\/author\/alexben\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kostenlose Museen in Nizza f\u00fcr alle Einwohner der Metropolregion - Chic Riviera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chicriviera.com\/de\/2019\/11\/05\/kostenlose-museen-a-nice-fur-alle-einwohner-der-metropole\/","og_locale":"de_DE","og_type":"article","og_title":"Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole - Chic Riviera","og_description":"Le saviez-vous? Avec le PASS MUS\u00c9ES DE NICE, tous les ni\u00e7ois mais aussi tous les habitants de la M\u00e9tropole ont acc\u00e8s gratuitement \u00e0 tous les mus\u00e9es et galeries, pendant 3 ans( validit\u00e9 du pass). Qu\u2019est ce que la M\u00e9tropole? Premi\u00e8re en France, c\u2019est une structure intercommunale autour de la ville de Nice, qui regroupe 49 [&hellip;]","og_url":"https:\/\/chicriviera.com\/de\/2019\/11\/05\/kostenlose-museen-a-nice-fur-alle-einwohner-der-metropole\/","og_site_name":"Chic Riviera","article_publisher":"https:\/\/www.facebook.com\/ChicRivieracom\/","article_published_time":"2019-11-05T10:14:08+00:00","article_modified_time":"2024-04-07T09:18:06+00:00","og_image":[{"width":910,"height":640,"url":"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg","type":"image\/jpeg"}],"author":"Alex","twitter_card":"summary_large_image","twitter_creator":"@Chic_Riviera","twitter_site":"@Chic_Riviera","twitter_misc":{"Verfasst von":"Alex","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#article","isPartOf":{"@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/"},"author":{"name":"Alex","@id":"https:\/\/chicriviera.com\/es\/#\/schema\/person\/c563ec1d9481b6d038092938cde95a4b"},"headline":"Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole","datePublished":"2019-11-05T10:14:08+00:00","dateModified":"2024-04-07T09:18:06+00:00","mainEntityOfPage":{"@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/chicriviera.com\/es\/#organization"},"image":{"@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage"},"thumbnailUrl":"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg","articleSection":["Activit\u00e9s","France","Nice"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/","url":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/","name":"Kostenlose Museen in Nizza f\u00fcr alle Einwohner der Metropolregion - Chic Riviera","isPartOf":{"@id":"https:\/\/chicriviera.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage"},"image":{"@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage"},"thumbnailUrl":"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg","datePublished":"2019-11-05T10:14:08+00:00","dateModified":"2024-04-07T09:18:06+00:00","breadcrumb":{"@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#primaryimage","url":"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg","contentUrl":"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/11\/ba9f805d-64f8-4bdb-afe2-6f719ab20000-2.jpg","width":910,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/chicriviera.com\/2019\/11\/05\/les-musees-gratuits-a-nice-pour-tous-les-habitants-de-la-metropole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/chicriviera.com\/"},{"@type":"ListItem","position":2,"name":"Les mus\u00e9es gratuits \u00e0 Nice pour tous les habitants de la M\u00e9tropole"}]},{"@type":"WebSite","@id":"https:\/\/chicriviera.com\/es\/#website","url":"https:\/\/chicriviera.com\/es\/","name":"Schicke Riviera","description":"Das Beste an der C\u00f4te d'Azur: Restaurants, Str\u00e4nde, Ausflugsziele","publisher":{"@id":"https:\/\/chicriviera.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chicriviera.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/chicriviera.com\/es\/#organization","name":"Schicke Riviera","url":"https:\/\/chicriviera.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/chicriviera.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/03\/cropped-crfavicon.png","contentUrl":"https:\/\/chicriviera.com\/wp-content\/uploads\/2019\/03\/cropped-crfavicon.png","width":512,"height":512,"caption":"Chic Riviera"},"image":{"@id":"https:\/\/chicriviera.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ChicRivieracom\/","https:\/\/x.com\/Chic_Riviera","https:\/\/www.instagram.com\/chicriviera\/"]},{"@type":"Person","@id":"https:\/\/chicriviera.com\/es\/#\/schema\/person\/c563ec1d9481b6d038092938cde95a4b","name":"Alex","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/chicriviera.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0bb721c49cd74f5b36020571509cc39351075de1991c6145cdbecbab8cf22c82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0bb721c49cd74f5b36020571509cc39351075de1991c6145cdbecbab8cf22c82?s=96&d=mm&r=g","caption":"Alex"},"url":"https:\/\/chicriviera.com\/de\/author\/alexben\/"}]}},"_links":{"self":[{"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/posts\/2874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/comments?post=2874"}],"version-history":[{"count":15,"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/posts\/2874\/revisions"}],"predecessor-version":[{"id":2895,"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/posts\/2874\/revisions\/2895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/media\/2893"}],"wp:attachment":[{"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/media?parent=2874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/categories?post=2874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chicriviera.com\/de\/wp-json\/wp\/v2\/tags?post=2874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}